{"id":924,"count":7,"description":"","link":"https:\/\/moonpointer.com\/new\/tag\/darkness\/","name":"darkness","slug":"darkness","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/moonpointer.com\/new\/wp-json\/wp\/v2\/tags\/924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonpointer.com\/new\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/moonpointer.com\/new\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/moonpointer.com\/new\/wp-json\/wp\/v2\/posts?tags=924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}